{"id":1625,"date":"2021-04-28T13:54:59","date_gmt":"2021-04-28T11:54:59","guid":{"rendered":"https:\/\/buecherheroes.de\/?p=1625"},"modified":"2021-04-28T13:58:02","modified_gmt":"2021-04-28T11:58:02","slug":"es-war-wohl-letztendlich-bestimmung","status":"publish","type":"post","link":"https:\/\/buecherheroes.de\/index.php\/es-war-wohl-letztendlich-bestimmung\/","title":{"rendered":"Es war wohl letztendlich Bestimmung"},"content":{"rendered":"<p><strong>Marion Alexa M\u00fcller, Inhaberin des Periplaneta Verlags<\/strong><\/p>\n<figure id=\"attachment_1628\" aria-describedby=\"caption-attachment-1628\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" class=\"wp-image-1628 size-medium\" src=\"https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/MarionAMueller-e1619610750441-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/MarionAMueller-e1619610750441-300x300.jpg 300w, https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/MarionAMueller-e1619610750441-150x150.jpg 150w, https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/MarionAMueller-e1619610750441.jpg 591w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-1628\" class=\"wp-caption-text\">\u00a9 Periplaneta<\/figcaption><\/figure>\n<p class=\"frage\">Das hat mich in die Buchbranche gef\u00fchrt:<\/p>\n<p>Schon w\u00e4hrend meines Studiums (zuerst Germanistik, dann Restaurierung von audiovisuellen Medien), habe ich B\u00fccher f\u00fcr Magazine rezensiert, war auf Leseb\u00fchnen unterwegs und habe Auftr\u00e4ge zur H\u00f6rbuchproduktion angenommen \u2013 damals noch ohne eigne ISBNs. Um diese L\u00fccke zu schlie\u00dfen, gr\u00fcndete ich 2007 den Periplaneta Verlag, 2009 kam das Literaturcaf\u00e9 dazu, 2012 der Imprint Edition Subkultur.<br \/>\nEs war wohl letztendlich Bestimmung. Die Leidenschaft f\u00fcr kreative Konzepte, f\u00fcr Stimmen, die etwas zu sagen haben und weil es Spa\u00df macht, aus einer guten Geschichte ein sch\u00f6nes Buch zu machen. Und weil das Verlegen von B\u00fcchern \u2013 auch wenn es pathetisch klingt \u2013 eine gro\u00dfe Freiheit ist und mir gro\u00dfe Freiheit erm\u00f6glicht.<\/p>\n<p class=\"frage\">Mein Lieblingsbuch das keiner kennt:<\/p>\n<p>\u00bbIsmaels Geheimnis\u00ab von Daniel Quinn \u2013 ein Gorilla erkl\u00e4rt die Welt.<\/p>\n<p class=\"frage\">Ohne meine Kolleg*innen h\u00e4tte ich dieses Ding nicht gedreht:<\/p>\n<p>Weil unser Periplaneta Literaturcaf\u00e9 seit geraumer Zeit geschlossen ist, drehen wir gerade die ersten beiden Folgen von TresenLesen-Online. Ohne Veranstaltungen ist es ja kaum auszuhalten. TresenLesen-Online wird eine Mischung aus moderierter Leseb\u00fchne, Poetry-Clips, Autorenlesungen, Musik und Kneipe f\u00fcr zuhause. B.Y.O.B. \ud83d\ude42<\/p>\n<p class=\"frage\">Dieses Projekt w\u00fcrde ich gerne aus der Schublade holen:<\/p>\n<p>Endlich den G\u00f6tterbaum im Vorgarten f\u00e4llen und eine Outdoor-B\u00fchne er\u00f6ffnen.<\/p>\n<p class=\"frage\">Ich bin Mitglied im B\u00f6rsenverein, weil&#8230;<\/p>\n<p>&#8230; ich mich hier gut aufgehoben f\u00fchle. Durch den B\u00f6rsenverein bekomme ich Informationen, Unterst\u00fctzung und Inspiration und es er\u00f6ffnen sich immer wieder neue M\u00f6glichkeiten zur Interaktion.<\/p>\n<p class=\"frage\">Welcher b\u00fccherHERO ist noch zu entdecken, und warum?<\/p>\n<p>Wegen des unstillbaren B\u00fccherhungers meines kleinen Sohnes ist die ehrliche Antwort: meine Stadtteilbibliothek. Ich w\u00e4re sonst schon hoffnungslos verarmt. Doch mein b\u00fccherHERO Nr. 2 (nur knapp hinter der Stadtteilbibliothek) ist der super sch\u00f6ne Buchladen <a href=\"https:\/\/www.genialokal.de\/buchhandlung\/berlin-prenzlauer-berg\/neueskapitel\/\" target=\"_blank\" rel=\"noopener\">Neues Kapitel<\/a> in der Kopenhagener Stra\u00dfe. Sobald man die schwere T\u00fcr aufgestemmt hat, f\u00fchlt man sich dort wohl und gut aufgehoben und will eigentlich gar nicht wieder gehen.<\/p>\n<div>\n<figure id=\"attachment_1629\" aria-describedby=\"caption-attachment-1629\" style=\"width: 1120px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" class=\"wp-image-1629 size-full\" src=\"https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/subkultur.jpg\" alt=\"\" width=\"1120\" height=\"630\" srcset=\"https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/subkultur.jpg 1120w, https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/subkultur-300x169.jpg 300w, https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/subkultur-1024x576.jpg 1024w, https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/subkultur-768x432.jpg 768w\" sizes=\"(max-width: 1120px) 100vw, 1120px\" \/><figcaption id=\"caption-attachment-1629\" class=\"wp-caption-text\">\u00a9 Periplaneta<\/figcaption><\/figure>\n<\/div>\n<div><\/div>\n<div class=\"abbinder\">Periplaneta Verlag<br \/>\nBornholmer Str. 81a<br \/>\n10439 Berlin-Prenzlauer Berg<\/p>\n<p>Telefon: (030) 44 67 34 34<br \/>\nE-Mail: <a href=\"mailto:hq@periplaneta.com\">hq@periplaneta.com<\/a><br \/>\nWebseite: <a href=\"http:\/\/www.periplaneta.com\" target=\"_blank\" rel=\"noopener\">www.periplaneta.com<\/a><\/p>\n<p>Facebook: <a href=\"https:\/\/www.facebook.com\/periplanetaverlag\" target=\"_blank\" rel=\"noopener\">periplanetaverlag<\/a><br \/>\nInstagram: <a href=\"https:\/\/www.instagram.com\/periplanetaner\/\" target=\"_blank\" rel=\"noopener\">periplanetaner<\/a><br \/>\nTwitter: <a href=\"https:\/\/twitter.com\/periplaneta\" target=\"_blank\" rel=\"noopener\">periplaneta<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Marion Alexa M\u00fcller, Periplaneta<\/p>\n","protected":false},"author":1,"featured_media":1633,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,5],"tags":[],"blocksy_meta":"","_links":{"self":[{"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/posts\/1625"}],"collection":[{"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/comments?post=1625"}],"version-history":[{"count":6,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/posts\/1625\/revisions"}],"predecessor-version":[{"id":1636,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/posts\/1625\/revisions\/1636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/media\/1633"}],"wp:attachment":[{"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/media?parent=1625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/categories?post=1625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/tags?post=1625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}