{"id":1621,"date":"2021-04-29T11:30:06","date_gmt":"2021-04-29T09:30:06","guid":{"rendered":"https:\/\/buecherheroes.de\/?p=1621"},"modified":"2021-04-29T11:30:06","modified_gmt":"2021-04-29T09:30:06","slug":"buch-ans-kind","status":"publish","type":"post","link":"https:\/\/buecherheroes.de\/index.php\/buch-ans-kind\/","title":{"rendered":"Buch ans Kind!"},"content":{"rendered":"<p><strong>Wiebke Schleser, Inhaberin von BuchSegler \u2013 Der Kinderbuchladen<\/strong><\/p>\n<figure id=\"attachment_1638\" aria-describedby=\"caption-attachment-1638\" style=\"width: 300px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" class=\"wp-image-1638 size-medium\" src=\"https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/image001-scaled-e1619688501283-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/image001-scaled-e1619688501283-300x300.jpg 300w, https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/image001-scaled-e1619688501283-150x150.jpg 150w, https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/image001-scaled-e1619688501283-768x768.jpg 768w, https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/image001-scaled-e1619688501283.jpg 902w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-1638\" class=\"wp-caption-text\">\u00a9 privat<\/figcaption><\/figure>\n<p class=\"frage\">Das hat mich in die Buchbranche gef\u00fchrt:<\/p>\n<p>Ich bin vernarrt in die Sch\u00f6nheit des Zusammenspiels von Illustration und Text im Bilderbuch, mag besondere Geschichten, gern mit einem offenem Ende. Ich freue mich, wenn der Funke meiner Begeisterung \u00fcber ein Buch, einer Geschichte, einem einzelnen Charakter auf ein Kind \u00fcberspringt und es zu lesen beginnt, oder einfach nur zu h\u00f6ren mag.<br \/>\nBuch ans Kind!<\/p>\n<p class=\"frage\">Mein Lieblingsbuch das keiner kennt:<\/p>\n<p>Franz F\u00fchmann \u00bbLob des Ungehorsams\u00ab, mit Illustrationen von Kristina Andres<\/p>\n<p class=\"frage\">Ohne meine Kolleg*innen h\u00e4tte ich dieses Ding nicht gedreht:<\/p>\n<p>Adventsschaufenster 2020 &#8211; wir stellten vom 01.12.2020 &#8211; 07.01.2021 t\u00e4glich einen Verlag mit Steckbrief und Lieblingsbuch im Schaufenster vor. Das bedeutete: Fragen f\u00fcr die Verlage ausdenken, diese f\u00fcr die Pr\u00e4sentation im Schaufenster aufbereiten, B\u00fccher ausw\u00e4hlen und t\u00e4glich das Schaufenster entsprechend neu dekorieren, Fotos f\u00fcr Instagram machen und t\u00e4glich posten. In den Weihnachtsferien schenkten wir den Kindern aus dem Kiez ein Quiz, das sich auf die vorgestellten Verlage im Schaufenster bezog und dem Gewinner eines der Lieblingsb\u00fccher.<\/p>\n<p class=\"frage\">Dieses Projekt w\u00fcrde ich gerne aus der Schublade holen:<\/p>\n<p>Ich m\u00f6chte gern unsere Lesecrew, Kinder zwischen 8 &#8211; 12Jahre, wieder aktiv mit ins Boot holen, mit ihnen \u00fcber Neuerscheinungen, Cover, Charaktere diskutieren, ihre Freude an Geschichten teilen, N\u00e4chte im Buchladen mit Lesen verbringen &#8211; wenn dies nach Corona wieder m\u00f6glich ist.<br \/>\nDie Rezepte eines Kochbuchs w\u00fcrde ich gern mit den Kindern zubereiten, Favoriten herausfinden und am Ende an einer langen Tafel im BuchSegler mit gr\u00f6\u00dfter Freude verspeisen.<\/p>\n<p class=\"frage\">Ich bin Mitglied im B\u00f6rsenverein, weil&#8230;<\/p>\n<p>&#8230; eine unabh\u00e4ngige Buchhandlung durch einen Interessenverband einen \u00bbstarken R\u00fccken\u00ab erh\u00e4lt. Die Kommunikation des Verbandes ist bereichernd und bringt Buchhandlungen untereinander, aber auch Buchhandlungen und Verlage auf unterschiedlichsten Eben in Verbindung.<br \/>\nUrheberrecht und Buchpreisbindung sind wesentliche Themen, f\u00fcr die sich der B\u00f6rsenverein vehement einsetzt und dies gilt es in unser aller Interesse zu unterst\u00fctzen.<\/p>\n<p class=\"frage\">Welcher b\u00fccherHERO ist noch zu entdecken, und warum?<\/p>\n<p><a href=\"http:\/\/www.mundoazul.de\" target=\"_blank\" rel=\"noopener\">Mundo azul<\/a> ist eine internationale Kinderbuchhandlung mit dem Schwerpunkt illustrierte Kinderb\u00fccher und besondere Buchprojekte aus aller Welt.<br \/>\nSie machen die Welt gr\u00f6\u00dfer und weiter und gleichzeitig bringen sie uns durch die Kinderb\u00fccher ganz nah.<\/p>\n<div>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-1639 size-full\" src=\"https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/IMG_1293-2.jpeg\" alt=\"\" width=\"1014\" height=\"442\" srcset=\"https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/IMG_1293-2.jpeg 1014w, https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/IMG_1293-2-300x131.jpeg 300w, https:\/\/buecherheroes.de\/wp-content\/uploads\/2021\/04\/IMG_1293-2-768x335.jpeg 768w\" sizes=\"(max-width: 1014px) 100vw, 1014px\" \/><\/p>\n<\/div>\n<div><\/div>\n<div class=\"abbinder\">Wiebke Schleser<br \/>\nBuchSegler \u2013 Der Kinderbuchladen<br \/>\nFlorastr. 88\/89<br \/>\n13187 Berlin-Pankow<\/p>\n<p>Telefon: (030) 43 72 41 20<br \/>\nE-Mail: <a href=\"mailto:info@buchsegler.de\">info@buchsegler.de<\/a><br \/>\nWebseite: <a href=\"https:\/\/www.buchsegler.de\" target=\"_blank\" rel=\"noopener\">www.buchsegler.de<\/a><\/p>\n<p>Instagram: <a href=\"https:\/\/www.instagram.com\/buchsegler\/\" target=\"_blank\" rel=\"noopener\">buchsegler<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wiebke Schleser, BuchSegler \u2013 Der Kinderbuchladen<\/p>\n","protected":false},"author":1,"featured_media":1638,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,9],"tags":[],"blocksy_meta":"","_links":{"self":[{"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/posts\/1621"}],"collection":[{"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/comments?post=1621"}],"version-history":[{"count":2,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/posts\/1621\/revisions"}],"predecessor-version":[{"id":1640,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/posts\/1621\/revisions\/1640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/media\/1638"}],"wp:attachment":[{"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/media?parent=1621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/categories?post=1621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/buecherheroes.de\/index.php\/wp-json\/wp\/v2\/tags?post=1621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}